{"id":1846,"date":"2015-10-19T16:37:43","date_gmt":"2015-10-19T14:37:43","guid":{"rendered":"http:\/\/www.amisdeuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/DSC05718.jpg"},"modified":"2016-10-17T10:49:08","modified_gmt":"2016-10-17T08:49:08","slug":"tessin_12_dsc05718","status":"inherit","type":"attachment","link":"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05718\/","title":{"rendered":"Tessin 12 Dsc05718"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1846","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=300%2C200&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?resize=400%2C266&amp;ssl=1 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"1846\" data-permalink=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05718\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=472%2C314&amp;ssl=1\" data-orig-size=\"472,314\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05718\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=472%2C314&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":472,"height":314,"file":"2015\/10\/tessin_12_dsc05718.jpg","sizes":{"thumbnail":{"file":"tessin_12_dsc05718-150x100.jpg","width":150,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=150%2C100&ssl=1"},"medium":{"file":"tessin_12_dsc05718-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=300%2C200&ssl=1"},"home":{"file":"tessin_12_dsc05718-400x266.jpg","width":400,"height":266,"mime_type":"image\/jpeg","source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718-400x266.jpg"},"full":{"file":"tessin_12_dsc05718.jpg?fit=472%2C314&ssl=1","width":472,"height":314,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=472%2C314&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1840,"source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg","_links":{"self":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media\/1846"}],"collection":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/users\/1"}]}}