{"id":4718,"date":"2016-10-03T14:33:22","date_gmt":"2016-10-03T12:33:22","guid":{"rendered":"http:\/\/www.amisdeuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/IMG_20160925_110132.jpg"},"modified":"2016-10-12T16:35:18","modified_gmt":"2016-10-12T14:35:18","slug":"lipsheim_16_img_20160925_110132","status":"inherit","type":"attachment","link":"https:\/\/www.deuxchevaux.ch\/wordpress\/lipsheim-2016\/lipsheim_16_img_20160925_110132\/","title":{"rendered":"Lipsheim 16 Img 20160925 110132"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-4718","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?resize=1440%2C1080&amp;ssl=1 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"4718\" data-permalink=\"https:\/\/www.deuxchevaux.ch\/wordpress\/lipsheim-2016\/lipsheim_16_img_20160925_110132\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=2048%2C1536&amp;ssl=1\" data-orig-size=\"2048,1536\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lipsheim 16 Img 20160925 110132\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1536,"file":"2016\/10\/lipsheim_16_img_20160925_110132.jpg","sizes":{"thumbnail":{"file":"lipsheim_16_img_20160925_110132-150x113.jpg","width":150,"height":113,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=150%2C113&ssl=1"},"medium":{"file":"lipsheim_16_img_20160925_110132-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"lipsheim_16_img_20160925_110132-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=768%2C576&ssl=1"},"large":{"file":"lipsheim_16_img_20160925_110132-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=1024%2C768&ssl=1"},"post-thumbnail":{"file":"lipsheim_16_img_20160925_110132-1440x1080.jpg","width":1440,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132-1440x1080.jpg"},"fluida-featured":{"file":"lipsheim_16_img_20160925_110132-1440x1440.jpg","width":1440,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132-1440x1440.jpg"},"fluida-header":{"file":"lipsheim_16_img_20160925_110132-1920x300.jpg","width":1920,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132-1920x300.jpg"},"full":{"file":"lipsheim_16_img_20160925_110132.jpg?fit=2048%2C1536&ssl=1","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg?fit=2048%2C1536&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4712,"source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/lipsheim_16_img_20160925_110132.jpg","_links":{"self":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media\/4718"}],"collection":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/users\/1"}]}}