{"id":4978,"date":"2016-10-23T12:27:18","date_gmt":"2016-10-23T10:27:18","guid":{"rendered":"http:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/IMG-20161020-WA0010.jpg"},"modified":"2016-10-23T12:47:16","modified_gmt":"2016-10-23T10:47:16","slug":"unser_hoeck_garage_16_img-20161020-wa0010","status":"inherit","type":"attachment","link":"https:\/\/www.deuxchevaux.ch\/wordpress\/der-hoeck-vom-19-oktober-2016-bei-georg-im-garage\/unser_hoeck_garage_16_img-20161020-wa0010\/","title":{"rendered":"Unser Hoeck Garage 16 Img 20161020 Wa0010"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-4978","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?resize=150%2C113&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?resize=400%2C300&amp;ssl=1 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"4978\" data-permalink=\"https:\/\/www.deuxchevaux.ch\/wordpress\/der-hoeck-vom-19-oktober-2016-bei-georg-im-garage\/unser_hoeck_garage_16_img-20161020-wa0010\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=1600%2C1200&amp;ssl=1\" data-orig-size=\"1600,1200\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Unser Hoeck Garage 16 Img 20161020 Wa0010\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1200,"file":"2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg","sizes":{"thumbnail":{"file":"unser_hoeck_garage_16_img-20161020-wa0010-150x113.jpg","width":150,"height":113,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=150%2C113&ssl=1"},"medium":{"file":"unser_hoeck_garage_16_img-20161020-wa0010-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"unser_hoeck_garage_16_img-20161020-wa0010-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=768%2C576&ssl=1"},"large":{"file":"unser_hoeck_garage_16_img-20161020-wa0010-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=1024%2C768&ssl=1"},"home":{"file":"unser_hoeck_garage_16_img-20161020-wa0010-400x300.jpg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010-400x300.jpg"},"featured-img":{"file":"unser_hoeck_garage_16_img-20161020-wa0010-840x410.jpg","width":840,"height":410,"mime_type":"image\/jpeg","source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010-840x410.jpg"},"full":{"file":"unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=1600%2C1200&ssl=1","width":1600,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg?fit=1600%2C1200&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4995,"source_url":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2016\/10\/unser_hoeck_garage_16_img-20161020-wa0010.jpg","_links":{"self":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media\/4978"}],"collection":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/users\/1"}]}}