{"id":1840,"date":"2012-10-05T16:30:34","date_gmt":"2012-10-05T14:30:34","guid":{"rendered":"http:\/\/www.amisdeuxchevaux.ch\/wordpress\/?p=1840"},"modified":"2016-10-17T21:24:01","modified_gmt":"2016-10-17T19:24:01","slug":"das-tessin-treffen-2012","status":"publish","type":"post","link":"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/","title":{"rendered":"Das Tessin Treffen 2012"},"content":{"rendered":"<p>Schon wieder ein Eintrag vom Tessin \u2013 wie doch die Zeit vergeht.<\/p>\n<p>Stefi ihre Eltern und \u201eR\u00e4ffu&#8220; bescherten uns wieder ein ganz toll organisiertes Treffen.<\/p>\n<p>An dieser Stelle ein gaaaanz grosses DANKESCH\u00d6N an die Organisatoren.<\/p>\n<p>Wieder mit Minestrone, Teigwaren, Wein, Bier und Grappa.<\/p>\n<p>&nbsp;<\/p>\n<p>Wie \u00fcblich trifft man sich im Tessin um einander einen guten Winter zu w\u00fcnschen.<\/p>\n<p>Ist es doch f\u00fcr die meisten das Treffen mit welchem man die Saison beendet.<\/p>\n<p>Aber auch Instandhaltungsarbeiten werden im Tessin ausgef\u00fchrt wie zum Beispiel das Zelt waschen.<\/p>\n<p>In diesem Jahr besonders gr\u00fcndlich.<\/p>\n<p>Soviel Regen \u2013 wobei Regen noch sehr wohlwollend formuliert ist.<\/p>\n<p>\u201eGschiffet hets in Str\u00f6men&#8220;. Wieder einmal fliessend Wasser \u2013 leider quer durchs Zelt.<\/p>\n<p>So \u2013 fertig gejammert.<\/p>\n<p>Es ist sehr interessant, dass man immer im Tessin die ideenreichsten Konstruktionen sieht.<\/p>\n<p>Auch in diesem Jahr.<\/p>\n<p>Grosse Aufmerksamkeit zog ein Gespann aus Bonn auf sich, welches aus einem 2CV 1960 und einem sehr sch\u00f6nen Wohnanh\u00e4nger sch\u00e4tzungsweise etwa gleichen Jahrgangs bestand. Ein mit gewichtsoptimierten Alustangen selbst gefertigtes Vorzelt war interessant.\u00a0 Montierbar passgenau auf eine Acadiane und wenn man das andere Ende nimmt passt es genau auf den \u201eWohnanh\u00e4nger&#8220;<\/p>\n<p>&nbsp;<\/p>\n<p>Ich reiste wie letztes Jahr bereits am Donnerstag ins Tessin. Nat\u00fcrlich wieder \u00fcber den Gotthardpass und die Tremola runter. Der Test schien mir angemessen um die selbst revidierte Bremsanlage zu pr\u00fcfen.<\/p>\n<p>Am Freitag hatte ich einen Termin.<\/p>\n<p>Mit Harald, Norbert und Jochen wollten wir zuoberst ins Maggiatal fahren.<\/p>\n<p>Abgemacht \u2013 einander begr\u00fcsst und los geht\u2019s. Harald und Claudia \u00fcbernehmen die F\u00fchrung. Manch einer ahnt weshalb. Es werden Fotos geschossen was das Zeugs h\u00e4lt. Es war interessant einmal zusehen zu k\u00f6nne wie die Fotos im\u00a0 Entenschnabel zustande kommen.<\/p>\n<p>N\u00e4mlich mit harter Arbeit \u2013 jawohl was der Harald da herum gerannt ist J alle Achtung.<\/p>\n<p>Nach diversen Zwischenhalten kamen wir nach dem ersten Stausee auf einer Alp an. Dort verpflegten wir uns. Wir wollten schauen wie weit nach oben wir durch den einsetzenden Regen und dichter werden Nebel kommen.<\/p>\n<p>Nun wir schafften es nicht ganz zum oberen Stausee. Die Sicht betrug nun keine 20 Meter mehr.<\/p>\n<p>Wir beschlossen um zu kehren. Unterwegs witzelten wir noch ob es wohl m\u00f6glich w\u00e4re mit dem 2CV ins benachbarte Bedretto Tal zu fahren. Das ist das Tal welche die beiden Kantone Tessin und Wallis \u00fcber den Nufenenpass miteinander verbindet. Strasse\u00a0 ist auf der Strassenkarte keine eingetragen.<\/p>\n<p>Am n\u00e4chsten Stammtisch wusste ich sehr wohl wem ich das erz\u00e4hlen musste. Wenn das im Klub einer versucht hat, ist es sicherlich unser Hausi. Siehe da \u2013 jawohl das geht sagte er. Hausi hat das schon einmal gemacht. \u201ejaaa ich musste\u00a0 da schon mal den einen oder anderen Stein aus dem Weg r\u00e4umen \u2013 g\u00e4ll&#8220;.<\/p>\n<p>Irgendwann kamen wir auch wieder zur\u00fcck ins \u201eCamp&#8220;.<\/p>\n<p>Gem\u00fctliches beisammen sitzen stand im Vordergrund \u2013 vorwiegend an noch trockenen Stellen.<\/p>\n<p>Der Italienische Acadiane Oasi \u2013 Fahrer aus Varese war auch wieder anwesend. Wir tauschten so gut es ging Erfahrungen aus. Er schenkte mir ein T-Shirt mit dem Original Schriftzug Oasi drauf.<\/p>\n<p>Author <em>R\u00f6ne<\/em><\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1170\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/www.deuxchevaux.ch\\\/wordpress\\\/das-tessin-treffen-2012\\\/&quot;,&quot;likes_blog_id&quot;:100715030}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05853\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1900\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05853\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05853.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05853\" alt=\"Tessin 12 Dsc05853\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05848\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1899\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05848\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05848.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05848\" alt=\"Tessin 12 Dsc05848\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05836\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1898\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05836\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05836.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05836\" alt=\"Tessin 12 Dsc05836\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 261px;\" data-original-width=\"1170\" data-original-height=\"261\" > <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05833\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1897\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05833\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05833.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05833\" alt=\"Tessin 12 Dsc05833\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05830\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1896\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05830\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05830.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05830\" alt=\"Tessin 12 Dsc05830\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05829\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1895\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05829\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05829.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05829\" alt=\"Tessin 12 Dsc05829\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05824\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1894\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05824\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05824.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05824\" alt=\"Tessin 12 Dsc05824\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05808\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1893\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05808\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05808.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05808\" alt=\"Tessin 12 Dsc05808\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05806\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1892\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05806\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05806.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05806\" alt=\"Tessin 12 Dsc05806\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 391px;\" data-original-width=\"1170\" data-original-height=\"391\" > <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05800\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1891\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05800\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05800.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05800\" alt=\"Tessin 12 Dsc05800\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05796\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1890\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05796\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05796.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05796\" alt=\"Tessin 12 Dsc05796\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05795\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1889\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05795\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05795.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05795\" alt=\"Tessin 12 Dsc05795\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05794\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1888\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05794\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05794.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05794\" alt=\"Tessin 12 Dsc05794\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05793\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1887\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05793\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05793.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05793\" alt=\"Tessin 12 Dsc05793\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 261px;\" data-original-width=\"1170\" data-original-height=\"261\" > <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05784\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1886\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05784\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05784.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05784\" alt=\"Tessin 12 Dsc05784\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05783\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1885\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05783\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05783.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05783\" alt=\"Tessin 12 Dsc05783\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05782\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1884\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05782\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05782.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05782\" alt=\"Tessin 12 Dsc05782\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05781\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1883\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05781\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05781.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05781\" alt=\"Tessin 12 Dsc05781\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05780\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1882\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05780\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05780.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05780\" alt=\"Tessin 12 Dsc05780\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05779\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1881\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05779\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05779.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05779\" alt=\"Tessin 12 Dsc05779\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 391px;\" data-original-width=\"1170\" data-original-height=\"391\" > <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05778\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1880\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05778\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05778.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05778\" alt=\"Tessin 12 Dsc05778\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05776\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1879\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05776\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05776.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05776\" alt=\"Tessin 12 Dsc05776\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05775\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1878\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05775\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05775.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05775\" alt=\"Tessin 12 Dsc05775\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05774\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1877\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05774\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05774.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05774\" alt=\"Tessin 12 Dsc05774\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05770\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1876\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05770\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05770.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05770\" alt=\"Tessin 12 Dsc05770\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 261px;\" data-original-width=\"1170\" data-original-height=\"261\" > <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05769\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1875\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05769\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05769.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05769\" alt=\"Tessin 12 Dsc05769\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05767\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1874\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05767\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05767.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05767\" alt=\"Tessin 12 Dsc05767\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05765\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1873\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05765\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05765.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05765\" alt=\"Tessin 12 Dsc05765\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05763\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1872\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05763\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05763.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05763\" alt=\"Tessin 12 Dsc05763\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05762\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1871\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05762\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05762.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05762\" alt=\"Tessin 12 Dsc05762\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05761\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1870\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05761\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05761.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05761\" alt=\"Tessin 12 Dsc05761\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 391px;\" data-original-width=\"1170\" data-original-height=\"391\" > <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05760\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1869\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05760\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05760.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05760\" alt=\"Tessin 12 Dsc05760\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05759\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1868\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05759\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05759.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05759\" alt=\"Tessin 12 Dsc05759\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05757\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1867\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05757\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05757.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05757\" alt=\"Tessin 12 Dsc05757\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05755\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1866\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05755\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05755.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05755\" alt=\"Tessin 12 Dsc05755\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05754\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1865\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05754\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05754.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05754\" alt=\"Tessin 12 Dsc05754\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 261px;\" data-original-width=\"1170\" data-original-height=\"261\" > <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05752\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1864\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05752\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05752.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05752\" alt=\"Tessin 12 Dsc05752\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05751\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1863\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05751\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05751.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05751\" alt=\"Tessin 12 Dsc05751\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05747\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1862\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05747\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05747.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05747\" alt=\"Tessin 12 Dsc05747\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05744\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1861\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05744\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05744.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05744\" alt=\"Tessin 12 Dsc05744\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05743\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1860\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05743\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05743.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05743\" alt=\"Tessin 12 Dsc05743\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05741\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1859\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05741\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05741.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05741\" alt=\"Tessin 12 Dsc05741\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 391px;\" data-original-width=\"1170\" data-original-height=\"391\" > <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05740\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1858\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05740\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05740.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05740\" alt=\"Tessin 12 Dsc05740\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05738\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1857\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05738\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05738.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05738\" alt=\"Tessin 12 Dsc05738\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05737\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1856\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05737\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05737.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05737\" alt=\"Tessin 12 Dsc05737\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05733\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1855\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05733\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05733.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05733\" alt=\"Tessin 12 Dsc05733\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05732\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1854\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05732\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05732.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05732\" alt=\"Tessin 12 Dsc05732\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 261px;\" data-original-width=\"1170\" data-original-height=\"261\" > <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05731\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1853\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05731\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05731.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05731\" alt=\"Tessin 12 Dsc05731\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05728\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1852\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05728\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05728.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05728\" alt=\"Tessin 12 Dsc05728\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 390px; height: 261px;\" data-original-width=\"390\" data-original-height=\"261\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05727\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"386\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1851\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05727\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?w=386&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05727.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"386\" height=\"257\" loading=\"lazy\" data-original-width=\"386\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05727\" alt=\"Tessin 12 Dsc05727\" style=\"width: 386px; height: 257px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05724\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1850\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05724\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05724.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05724\" alt=\"Tessin 12 Dsc05724\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05723\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1849\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05723\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05723.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05723\" alt=\"Tessin 12 Dsc05723\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05722\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1848\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05722\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05722.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05722\" alt=\"Tessin 12 Dsc05722\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 391px;\" data-original-width=\"1170\" data-original-height=\"391\" > <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05720\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1847\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05720\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05720.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05720\" alt=\"Tessin 12 Dsc05720\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 585px; height: 391px;\" data-original-width=\"585\" data-original-height=\"391\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05718\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"581\"> <meta itemprop=\"height\" content=\"387\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1846\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05718\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?w=581&#038;h=387&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05718.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"581\" height=\"387\" loading=\"lazy\" data-original-width=\"581\" data-original-height=\"387\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05718\" alt=\"Tessin 12 Dsc05718\" style=\"width: 581px; height: 387px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 521px;\" data-original-width=\"1170\" data-original-height=\"521\" > <div class=\"gallery-group images-1\" style=\"width: 781px; height: 521px;\" data-original-width=\"781\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05716\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"777\"> <meta itemprop=\"height\" content=\"517\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1845\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05716\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?w=777&#038;h=517&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05716.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"777\" height=\"517\" loading=\"lazy\" data-original-width=\"777\" data-original-height=\"517\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05716\" alt=\"Tessin 12 Dsc05716\" style=\"width: 777px; height: 517px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 389px; height: 521px;\" data-original-width=\"389\" data-original-height=\"521\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05711\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"257\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1844\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05711\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?w=385&#038;h=257&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05711.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"257\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"257\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05711\" alt=\"Tessin 12 Dsc05711\" style=\"width: 385px; height: 257px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05708\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"385\"> <meta itemprop=\"height\" content=\"256\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1843\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05708\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?w=385&#038;h=256&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05708.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"385\" height=\"256\" loading=\"lazy\" data-original-width=\"385\" data-original-height=\"256\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05708\" alt=\"Tessin 12 Dsc05708\" style=\"width: 385px; height: 256px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1170px; height: 780px;\" data-original-width=\"1170\" data-original-height=\"780\" > <div class=\"gallery-group images-1\" style=\"width: 1170px; height: 780px;\" data-original-width=\"1170\" data-original-height=\"780\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.deuxchevaux.ch\/wordpress\/das-tessin-treffen-2012\/tessin_12_dsc05700\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"1166\"> <meta itemprop=\"height\" content=\"776\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1842\" data-orig-file=\"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg\" data-orig-size=\"472,314\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tessin 12 Dsc05700\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?fit=472%2C314&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?w=1166&#038;h=776&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?w=472&amp;ssl=1 472w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?resize=400%2C266&amp;ssl=1 400w\" width=\"1166\" height=\"776\" loading=\"lazy\" data-original-width=\"1166\" data-original-height=\"776\" itemprop=\"http:\/\/schema.org\/image\" title=\"Tessin 12 Dsc05700\" alt=\"Tessin 12 Dsc05700\" style=\"width: 1166px; height: 776px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Schon wieder ein Eintrag vom Tessin \u2013 wie doch die Zeit vergeht. Stefi ihre Eltern und \u201eR\u00e4ffu&#8220; bescherten uns wieder ein ganz [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,15],"tags":[],"class_list":["post-1840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club","category-treffen"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.deuxchevaux.ch\/wordpress\/wp-content\/uploads\/2015\/10\/tessin_12_dsc05700.jpg?fit=472%2C314&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/posts\/1840"}],"collection":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=1840"}],"version-history":[{"count":4,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/posts\/1840\/revisions"}],"predecessor-version":[{"id":4938,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/posts\/1840\/revisions\/4938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media\/1842"}],"wp:attachment":[{"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=1840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=1840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deuxchevaux.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=1840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}